{"id":1190,"date":"2021-06-05T16:11:52","date_gmt":"2021-06-05T14:11:52","guid":{"rendered":"https:\/\/baslux.pl\/basluxn\/?p=1190"},"modified":"2021-07-02T10:45:36","modified_gmt":"2021-07-02T08:45:36","slug":"przeciwprad-stp-95m3-400-v-4kw","status":"publish","type":"post","link":"https:\/\/basenypoliestrowe.pl\/de\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw","title":{"rendered":""},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,35],"tags":[],"class_list":["post-1190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-akcesoria","category-atrakcje-wodne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"pl_PL\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basenypoliestrowe.pl\/de\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basenybaslux\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-05T14:11:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-02T08:45:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"803\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"\u0141ukasz Nowak\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0141ukasz Nowak\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#article\",\"isPartOf\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw\"},\"author\":{\"name\":\"\u0141ukasz Nowak\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a\"},\"headline\":\"Kein Titel\",\"datePublished\":\"2021-06-05T14:11:52+00:00\",\"dateModified\":\"2021-07-02T08:45:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw\"},\"wordCount\":739,\"publisher\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png\",\"articleSection\":[\"Akcesoria\",\"Atrakcje wodne\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw\",\"url\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png\",\"datePublished\":\"2021-06-05T14:11:52+00:00\",\"dateModified\":\"2021-07-02T08:45:36+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage\",\"url\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png\",\"contentUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png\",\"width\":1600,\"height\":803},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#website\",\"url\":\"https:\/\/basenypoliestrowe.pl\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/basenypoliestrowe.pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\",\"name\":\"Baslux\",\"url\":\"https:\/\/basenypoliestrowe.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png\",\"contentUrl\":\"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png\",\"width\":318,\"height\":42,\"caption\":\"Baslux\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/basenybaslux\",\"https:\/\/www.youtube.com\/channel\/UC9HZsB-mzFrRgXpc4k0g-Hg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a\",\"name\":\"\u0141ukasz Nowak\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g\",\"caption\":\"\u0141ukasz Nowak\"},\"sameAs\":[\"https:\/\/padre.com.pl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"[:pl]Przeciwpr\u0105d STP 95m3, 400 V, 4kW[:] -","og_url":"https:\/\/basenypoliestrowe.pl\/de\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw","article_publisher":"https:\/\/www.facebook.com\/basenybaslux","article_published_time":"2021-06-05T14:11:52+00:00","article_modified_time":"2021-07-02T08:45:36+00:00","og_image":[{"width":1600,"height":803,"url":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png","type":"image\/png"}],"author":"\u0141ukasz Nowak","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"\u0141ukasz Nowak","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#article","isPartOf":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw"},"author":{"name":"\u0141ukasz Nowak","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a"},"headline":"Kein Titel","datePublished":"2021-06-05T14:11:52+00:00","dateModified":"2021-07-02T08:45:36+00:00","mainEntityOfPage":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw"},"wordCount":739,"publisher":{"@id":"https:\/\/basenypoliestrowe.pl\/#organization"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage"},"thumbnailUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png","articleSection":["Akcesoria","Atrakcje wodne"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw","url":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw","name":"","isPartOf":{"@id":"https:\/\/basenypoliestrowe.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage"},"thumbnailUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png","datePublished":"2021-06-05T14:11:52+00:00","dateModified":"2021-07-02T08:45:36+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-95m3-400-v-4kw#primaryimage","url":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png","contentUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/0180565.png","width":1600,"height":803},{"@type":"WebSite","@id":"https:\/\/basenypoliestrowe.pl\/#website","url":"https:\/\/basenypoliestrowe.pl\/","name":"","description":"","publisher":{"@id":"https:\/\/basenypoliestrowe.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basenypoliestrowe.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/basenypoliestrowe.pl\/#organization","name":"Baslux","url":"https:\/\/basenypoliestrowe.pl\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/","url":"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png","contentUrl":"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png","width":318,"height":42,"caption":"Baslux"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basenybaslux","https:\/\/www.youtube.com\/channel\/UC9HZsB-mzFrRgXpc4k0g-Hg"]},{"@type":"Person","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a","name":"\u0141ukasz Nowak","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g","caption":"\u0141ukasz Nowak"},"sameAs":["https:\/\/padre.com.pl"]}]}},"_links":{"self":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":0,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/media\/2325"}],"wp:attachment":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}