{"id":1294,"date":"2021-06-07T10:30:58","date_gmt":"2021-06-07T08:30:58","guid":{"rendered":"https:\/\/baslux.pl\/basluxn\/?p=1294"},"modified":"2021-07-29T12:50:28","modified_gmt":"2021-07-29T10:50:28","slug":"pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v","status":"publish","type":"post","link":"https:\/\/basenypoliestrowe.pl\/de\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v","title":{"rendered":""},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,39],"tags":[],"class_list":["post-1294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-akcesoria","category-ogrzewanie-wody-w-basenie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"pl_PL\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basenypoliestrowe.pl\/de\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basenybaslux\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-07T08:30:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T10:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0141ukasz Nowak\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0141ukasz Nowak\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#article\",\"isPartOf\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v\"},\"author\":{\"name\":\"\u0141ukasz Nowak\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a\"},\"headline\":\"Kein Titel\",\"datePublished\":\"2021-06-07T08:30:58+00:00\",\"dateModified\":\"2021-07-29T10:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v\"},\"wordCount\":802,\"publisher\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg\",\"articleSection\":[\"Akcesoria\",\"Ogrzewanie wody w basenie\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v\",\"url\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg\",\"datePublished\":\"2021-06-07T08:30:58+00:00\",\"dateModified\":\"2021-07-29T10:50:28+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage\",\"url\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg\",\"contentUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg\",\"width\":1024,\"height\":719},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#website\",\"url\":\"https:\/\/basenypoliestrowe.pl\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/basenypoliestrowe.pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\",\"name\":\"Baslux\",\"url\":\"https:\/\/basenypoliestrowe.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png\",\"contentUrl\":\"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png\",\"width\":318,\"height\":42,\"caption\":\"Baslux\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/basenybaslux\",\"https:\/\/www.youtube.com\/channel\/UC9HZsB-mzFrRgXpc4k0g-Hg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a\",\"name\":\"\u0141ukasz Nowak\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g\",\"caption\":\"\u0141ukasz Nowak\"},\"sameAs\":[\"https:\/\/padre.com.pl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"[:pl]Pompa ciep\u0142a TEBAS INVERTER o mocy 16,5 kW, 230 V[:] -","og_url":"https:\/\/basenypoliestrowe.pl\/de\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v","article_publisher":"https:\/\/www.facebook.com\/basenybaslux","article_published_time":"2021-06-07T08:30:58+00:00","article_modified_time":"2021-07-29T10:50:28+00:00","og_image":[{"width":1024,"height":719,"url":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg","type":"image\/jpeg"}],"author":"\u0141ukasz Nowak","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"\u0141ukasz Nowak","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#article","isPartOf":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v"},"author":{"name":"\u0141ukasz Nowak","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a"},"headline":"Kein Titel","datePublished":"2021-06-07T08:30:58+00:00","dateModified":"2021-07-29T10:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v"},"wordCount":802,"publisher":{"@id":"https:\/\/basenypoliestrowe.pl\/#organization"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage"},"thumbnailUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg","articleSection":["Akcesoria","Ogrzewanie wody w basenie"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v","url":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v","name":"","isPartOf":{"@id":"https:\/\/basenypoliestrowe.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage"},"thumbnailUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg","datePublished":"2021-06-07T08:30:58+00:00","dateModified":"2021-07-29T10:50:28+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/pompa-ciepla-tebas-inverter-o-mocy-165-kw-230-v#primaryimage","url":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg","contentUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/06\/14609.jpg","width":1024,"height":719},{"@type":"WebSite","@id":"https:\/\/basenypoliestrowe.pl\/#website","url":"https:\/\/basenypoliestrowe.pl\/","name":"","description":"","publisher":{"@id":"https:\/\/basenypoliestrowe.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basenypoliestrowe.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/basenypoliestrowe.pl\/#organization","name":"Baslux","url":"https:\/\/basenypoliestrowe.pl\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/","url":"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png","contentUrl":"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png","width":318,"height":42,"caption":"Baslux"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basenybaslux","https:\/\/www.youtube.com\/channel\/UC9HZsB-mzFrRgXpc4k0g-Hg"]},{"@type":"Person","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/3d995c228ae8fd2367b55b4d16dc008a","name":"\u0141ukasz Nowak","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d14a5cf1e93916ee7d3cb99109d8a7d13bb20d767340bf3998dcea7fdf91936f?s=96&d=mm&r=g","caption":"\u0141ukasz Nowak"},"sameAs":["https:\/\/padre.com.pl"]}]}},"_links":{"self":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/posts\/1294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/comments?post=1294"}],"version-history":[{"count":0,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/posts\/1294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/media\/2558"}],"wp:attachment":[{"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/media?parent=1294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/categories?post=1294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/de\/wp-json\/wp\/v2\/tags?post=1294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}