{"id":2363,"date":"2021-06-05T10:40:36","date_gmt":"2021-06-05T08:40:36","guid":{"rendered":"https:\/\/baslux.pl\/basluxn\/?p=2363"},"modified":"2021-07-02T10:41:46","modified_gmt":"2021-07-02T08:41:46","slug":"przeciwprad-stp-70m3-230-v-22-kw-2","status":"publish","type":"post","link":"https:\/\/basenypoliestrowe.pl\/en\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2","title":{"rendered":""},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,35],"tags":[],"class_list":["post-2363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-akcesoria","category-atrakcje-wodne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pl_PL\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basenypoliestrowe.pl\/en\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basenybaslux\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-05T08:40:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-02T08:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1337\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"basluxadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"basluxadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#article\",\"isPartOf\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2\"},\"author\":{\"name\":\"basluxadmin\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/270db50252ba4b2d874600b92316339c\"},\"headline\":\"No title\",\"datePublished\":\"2021-06-05T08:40:36+00:00\",\"dateModified\":\"2021-07-02T08:41:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2\"},\"wordCount\":685,\"publisher\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg\",\"articleSection\":[\"Akcesoria\",\"Atrakcje wodne\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2\",\"url\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg\",\"datePublished\":\"2021-06-05T08:40:36+00:00\",\"dateModified\":\"2021-07-02T08:41:46+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage\",\"url\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg\",\"contentUrl\":\"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg\",\"width\":1337,\"height\":916},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#website\",\"url\":\"https:\/\/basenypoliestrowe.pl\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/basenypoliestrowe.pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#organization\",\"name\":\"Baslux\",\"url\":\"https:\/\/basenypoliestrowe.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png\",\"contentUrl\":\"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png\",\"width\":318,\"height\":42,\"caption\":\"Baslux\"},\"image\":{\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/basenybaslux\",\"https:\/\/www.youtube.com\/channel\/UC9HZsB-mzFrRgXpc4k0g-Hg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/270db50252ba4b2d874600b92316339c\",\"name\":\"basluxadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/22f967de495c7b27faf6d4a54c4ffa25babcd8a80ee13cfc34dba13ac5f47194?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/22f967de495c7b27faf6d4a54c4ffa25babcd8a80ee13cfc34dba13ac5f47194?s=96&d=mm&r=g\",\"caption\":\"basluxadmin\"},\"sameAs\":[\"https:\/\/baslux.dkonto.pl\/basluxn\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"[:pl]Wylewka Bali po\u0142ysk\/mat stal A 316 przep\u0142yw 40 m3\/h[:] -","og_url":"https:\/\/basenypoliestrowe.pl\/en\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2","article_publisher":"https:\/\/www.facebook.com\/basenybaslux","article_published_time":"2021-06-05T08:40:36+00:00","article_modified_time":"2021-07-02T08:41:46+00:00","og_image":[{"width":1337,"height":916,"url":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg","type":"image\/jpeg"}],"author":"basluxadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"basluxadmin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#article","isPartOf":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2"},"author":{"name":"basluxadmin","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/270db50252ba4b2d874600b92316339c"},"headline":"No title","datePublished":"2021-06-05T08:40:36+00:00","dateModified":"2021-07-02T08:41:46+00:00","mainEntityOfPage":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2"},"wordCount":685,"publisher":{"@id":"https:\/\/basenypoliestrowe.pl\/#organization"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage"},"thumbnailUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg","articleSection":["Akcesoria","Atrakcje wodne"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2","url":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2","name":"","isPartOf":{"@id":"https:\/\/basenypoliestrowe.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage"},"thumbnailUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg","datePublished":"2021-06-05T08:40:36+00:00","dateModified":"2021-07-02T08:41:46+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basenypoliestrowe.pl\/akcesoria\/przeciwprad-stp-70m3-230-v-22-kw-2#primaryimage","url":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg","contentUrl":"https:\/\/basenypoliestrowe.pl\/wp-content\/uploads\/2021\/07\/380000.jpg","width":1337,"height":916},{"@type":"WebSite","@id":"https:\/\/basenypoliestrowe.pl\/#website","url":"https:\/\/basenypoliestrowe.pl\/","name":"","description":"","publisher":{"@id":"https:\/\/basenypoliestrowe.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basenypoliestrowe.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/basenypoliestrowe.pl\/#organization","name":"Baslux","url":"https:\/\/basenypoliestrowe.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/","url":"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png","contentUrl":"https:\/\/baslux.pl\/wp-content\/uploads\/2021\/05\/logo_baslux.png","width":318,"height":42,"caption":"Baslux"},"image":{"@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basenybaslux","https:\/\/www.youtube.com\/channel\/UC9HZsB-mzFrRgXpc4k0g-Hg"]},{"@type":"Person","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/270db50252ba4b2d874600b92316339c","name":"basluxadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basenypoliestrowe.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/22f967de495c7b27faf6d4a54c4ffa25babcd8a80ee13cfc34dba13ac5f47194?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22f967de495c7b27faf6d4a54c4ffa25babcd8a80ee13cfc34dba13ac5f47194?s=96&d=mm&r=g","caption":"basluxadmin"},"sameAs":["https:\/\/baslux.dkonto.pl\/basluxn"]}]}},"_links":{"self":[{"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/posts\/2363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/comments?post=2363"}],"version-history":[{"count":0,"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/posts\/2363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/media\/2365"}],"wp:attachment":[{"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/media?parent=2363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/categories?post=2363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basenypoliestrowe.pl\/en\/wp-json\/wp\/v2\/tags?post=2363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}